{"id":935,"date":"2020-12-15T05:47:00","date_gmt":"2020-12-15T04:47:00","guid":{"rendered":"https:\/\/www.cabinet-magar.fr\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/"},"modified":"2021-04-25T03:00:19","modified_gmt":"2021-04-25T01:00:19","slug":"donnees-de-sante-du-nouveau-pour-certains-professionnels","status":"publish","type":"post","link":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/","title":{"rendered":"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels !"},"content":{"rendered":"<p >Dans le cadre de leurs missions, les commissaires aux comptes et les prestataires informatiques ont acc\u00e8s aux donn\u00e9es de sant\u00e9 des patients des \u00e9tablissements de sant\u00e9. Celles-ci sont-elles suffisamment prot\u00e9g\u00e9es ? R\u00e9ponse\u2026<\/p>\n<div>\n<h2>Donn\u00e9es de sant\u00e9 : il faut des garanties !<\/h2>\n<p>La r\u00e9glementation autorise les commissaires aux comptes \u00e0 acc\u00e9der aux donn\u00e9es du dossier m\u00e9dical des patients des \u00e9tablissements de sant\u00e9 dans le cadre de leur mission de certification des comptes.<\/p>\n<p>Elle autorise \u00e9galement les prestataires informatiques \u00e0 acc\u00e9der \u00e0 ces donn\u00e9es m\u00e9dicales dans le cadre de leur mission.<\/p>\n<p>Ces donn\u00e9es portent sur l&#8217;identit\u00e9 du patient, son lieu de r\u00e9sidence, ses pathologies et les actes de diagnostic et de soins r\u00e9alis\u00e9s au cours de son s\u00e9jour dans l&#8217;\u00e9tablissement de sant\u00e9.<\/p>\n<p>Le juge vient d\u2019annuler cette r\u00e9glementation car elle n\u2019offre pas de garanties suffisantes quant \u00e0 la protection des donn\u00e9es individuelles de sant\u00e9, notamment au regard du R\u00e8glement G\u00e9n\u00e9ral sur la Protection des Donn\u00e9es (RGPD).<\/p>\n<p>Le Gouvernement va donc devoir revoir sa copie\u2026<\/p>\n<p>En attendant qu\u2019une nouvelle r\u00e9glementation soit mise en place, sachez que les commissaires aux comptes ne peuvent avoir acc\u00e8s qu\u2019\u00e0 des donn\u00e9es pseudonymis\u00e9es, \u00e0 moins de recourir au service d\u2019un m\u00e9decin expert, notamment un \u00ab m\u00e9decin DIM \u00bb d\u2019un autre \u00e9tablissement.<\/p>\n<p>Par ailleurs, le m\u00e9decin responsable de l\u2019information m\u00e9dicale des \u00e9tablissements de sant\u00e9 doit organiser et contr\u00f4ler le travail confi\u00e9 aux \u00e9ventuels prestataires informatiques plac\u00e9s sous sa responsabilit\u00e9.<\/p>\n<p><span style=\"text-decoration: underline;\">Source :<\/span> Arr\u00eat du Conseil d\u2019Etat du 25 novembre 2020, n\u00b0 428451<\/p>\n<p><a href=\"https:\/\/www.weblex.fr\/weblex-actualite\/donnees-de-sante-du-nouveau-pour-certains-professionnels\" target=\"_blank\" rel=\"noopener\">Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels !<\/a> \u00a9 Copyright WebLex &#8211; 2020<\/p>\n<\/div>\n<p><img src='https:\/\/www.weblex.fr\/images\/flux_actus\/cabinetmedical.jpg'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de leurs missions, les commissaires aux comptes et les prestataires informatiques ont acc\u00e8s aux donn\u00e9es de sant\u00e9 des patients des \u00e9tablissements de sant\u00e9. Celles-ci sont-elles suffisamment prot\u00e9g\u00e9es ? R\u00e9ponse\u2026<\/p>\n","protected":false},"author":0,"featured_media":4359,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,7],"tags":[],"class_list":["post-935","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-juridique","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels ! - Cabinet Magar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels ! - Cabinet Magar\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre de leurs missions, les commissaires aux comptes et les prestataires informatiques ont acc\u00e8s aux donn\u00e9es de sant\u00e9 des patients des \u00e9tablissements de sant\u00e9. Celles-ci sont-elles suffisamment prot\u00e9g\u00e9es ? R\u00e9ponse\u2026\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabinet Magar\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-15T04:47:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-25T01:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels !\",\"datePublished\":\"2020-12-15T04:47:00+00:00\",\"dateModified\":\"2021-04-25T01:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/\"},\"wordCount\":293,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg\",\"articleSection\":[\"Actu Juridique\",\"Actualit\u00e9s\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/\",\"url\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/\",\"name\":\"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels ! - Cabinet Magar\",\"isPartOf\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg\",\"datePublished\":\"2020-12-15T04:47:00+00:00\",\"dateModified\":\"2021-04-25T01:00:19+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#primaryimage\",\"url\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg\",\"contentUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.cabinet-magar.fr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels !\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/#website\",\"url\":\"https:\/\/www.cabinet-magar.fr\/\",\"name\":\"Cabinet Magar\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cabinet-magar.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels ! - Cabinet Magar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/","og_locale":"de_DE","og_type":"article","og_title":"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels ! - Cabinet Magar","og_description":"Dans le cadre de leurs missions, les commissaires aux comptes et les prestataires informatiques ont acc\u00e8s aux donn\u00e9es de sant\u00e9 des patients des \u00e9tablissements de sant\u00e9. Celles-ci sont-elles suffisamment prot\u00e9g\u00e9es ? R\u00e9ponse\u2026","og_url":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/","og_site_name":"Cabinet Magar","article_published_time":"2020-12-15T04:47:00+00:00","article_modified_time":"2021-04-25T01:00:19+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#article","isPartOf":{"@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/"},"author":{"name":"","@id":""},"headline":"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels !","datePublished":"2020-12-15T04:47:00+00:00","dateModified":"2021-04-25T01:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/"},"wordCount":293,"commentCount":0,"image":{"@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg","articleSection":["Actu Juridique","Actualit\u00e9s"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/","url":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/","name":"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels ! - Cabinet Magar","isPartOf":{"@id":"https:\/\/www.cabinet-magar.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#primaryimage"},"image":{"@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg","datePublished":"2020-12-15T04:47:00+00:00","dateModified":"2021-04-25T01:00:19+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#primaryimage","url":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg","contentUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cabinetmedical.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/donnees-de-sante-du-nouveau-pour-certains-professionnels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cabinet-magar.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Donn\u00e9es de sant\u00e9 : du nouveau pour certains professionnels !"}]},{"@type":"WebSite","@id":"https:\/\/www.cabinet-magar.fr\/#website","url":"https:\/\/www.cabinet-magar.fr\/","name":"Cabinet Magar","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cabinet-magar.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/comments?post=935"}],"version-history":[{"count":1,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/935\/revisions"}],"predecessor-version":[{"id":4358,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/935\/revisions\/4358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/media\/4359"}],"wp:attachment":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/media?parent=935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/categories?post=935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/tags?post=935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}