{"id":740,"date":"2021-01-18T05:59:00","date_gmt":"2021-01-18T04:59:00","guid":{"rendered":"https:\/\/www.cabinet-magar.fr\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/"},"modified":"2021-04-15T03:01:06","modified_gmt":"2021-04-15T01:01:06","slug":"coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion","status":"publish","type":"post","link":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/","title":{"rendered":"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union"},"content":{"rendered":"<p >Les voyageurs souhaitant se rendre de Mayotte, de Guyane ou de la R\u00e9union vers le reste de la France doivent pr\u00e9senter une d\u00e9claration sur l\u2019honneur au transporteur. Le contenu de cette d\u00e9claration vient d\u2019\u00eatre pr\u00e9cis\u00e9. Que faut-il y mentionner ?<\/p>\n<div>\n<h2>Coronavirus (COVID-19) : voyage en provenance de Mayotte, de Guyane et de la R\u00e9union = attestation<\/h2>\n<p>Depuis le 18 janvier 2021, il est pr\u00e9cis\u00e9 que toute personne se d\u00e9pla\u00e7ant depuis Mayotte, la Guyane ou la R\u00e9union vers le reste de la France doit pr\u00e9senter au transporteur, avant son embarquement, une d\u00e9claration sur l&#8217;honneur attestant :<\/p>\n<ul>\n<li>qu&#8217;elle ne pr\u00e9sente pas de sympt\u00f4me d&#8217;infection \u00e0 la covid-19 ;<\/li>\n<li>qu&#8217;elle n&#8217;a pas connaissance d&#8217;avoir \u00e9t\u00e9 en contact avec un cas confirm\u00e9 de covid-19 dans les 14 jours pr\u00e9c\u00e9dant son trajet ;<\/li>\n<li>si elle est \u00e2g\u00e9e de 11 ans ou plus, qu&#8217;elle accepte qu&#8217;un test ou un examen biologique de d\u00e9pistage virologique de d\u00e9tection du SARS-CoV-2 puisse \u00eatre r\u00e9alis\u00e9 \u00e0 son arriv\u00e9e sur le territoire national (les seuls tests pouvant \u00eatre r\u00e9alis\u00e9s sont ceux permettant la d\u00e9tection de la prot\u00e9ine N du SARS-CoV-2) ;<\/li>\n<li>qu&#8217;elle s&#8217;engage \u00e0 respecter un isolement prophylactique de 7 jours apr\u00e8s son arriv\u00e9e sur le territoire national et, si elle est \u00e2g\u00e9e de 11 ans ou plus, \u00e0 r\u00e9aliser, au terme de cette p\u00e9riode, un examen biologique de d\u00e9pistage virologique permettant la d\u00e9tection du SARS-CoV-2 (mesure non-applicable aux professionnels du transport routier).<\/li>\n<\/ul>\n<p>Si elle est \u00e2g\u00e9e de 11 ans ou plus, la personne doit aussi pr\u00e9senter le r\u00e9sultat d&#8217;un examen biologique de d\u00e9pistage virologique r\u00e9alis\u00e9 moins de 72 heures avant l&#8217;embarquement ne concluant pas \u00e0 une contamination par la covid-19.<\/p>\n<p>A d\u00e9faut de pr\u00e9sentation de l\u2019attestation et du r\u00e9sultat d\u2019un d\u00e9pistage n\u00e9gatif, l&#8217;embarquement est refus\u00e9 et la personne est reconduite \u00e0 l&#8217;ext\u00e9rieur des espaces concern\u00e9s.<\/p>\n<p><span style=\"text-decoration: underline;\">Source :<\/span> D\u00e9cret n\u00b0 2021-31 du 15 janvier 2021 modifiant les d\u00e9crets n\u00b0 2020-1262 du 16 octobre 2020 et n\u00b0 2020-1310 du 29 octobre 2020 prescrivant les mesures g\u00e9n\u00e9rales n\u00e9cessaires pour faire face \u00e0 l&#8217;\u00e9pid\u00e9mie de covid-19 dans le cadre de l&#8217;\u00e9tat d&#8217;urgence sanitaire<\/p>\n<p><a href=\"https:\/\/www.weblex.fr\/weblex-actualite\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\" target=\"_blank\" rel=\"noopener\">Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union<\/a> \u00a9 Copyright WebLex &#8211; 2021<\/p>\n<\/div>\n<p><img src='https:\/\/www.weblex.fr\/images\/flux_actus\/cayenne.jpg'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les voyageurs souhaitant se rendre de Mayotte, de Guyane ou de la R\u00e9union vers le reste de la France doivent pr\u00e9senter une d\u00e9claration sur l\u2019honneur au transporteur. Le contenu de cette d\u00e9claration vient d\u2019\u00eatre pr\u00e9cis\u00e9. Que faut-il y mentionner ?<\/p>\n","protected":false},"author":0,"featured_media":4025,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,7],"tags":[],"class_list":["post-740","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-juridique","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union - Cabinet Magar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union - Cabinet Magar\" \/>\n<meta property=\"og:description\" content=\"Les voyageurs souhaitant se rendre de Mayotte, de Guyane ou de la R\u00e9union vers le reste de la France doivent pr\u00e9senter une d\u00e9claration sur l\u2019honneur au transporteur. Le contenu de cette d\u00e9claration vient d\u2019\u00eatre pr\u00e9cis\u00e9. Que faut-il y mentionner ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabinet Magar\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-18T04:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-15T01:01:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union\",\"datePublished\":\"2021-01-18T04:59:00+00:00\",\"dateModified\":\"2021-04-15T01:01:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/\"},\"wordCount\":420,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg\",\"articleSection\":[\"Actu Juridique\",\"Actualit\u00e9s\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/\",\"url\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/\",\"name\":\"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union - Cabinet Magar\",\"isPartOf\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg\",\"datePublished\":\"2021-01-18T04:59:00+00:00\",\"dateModified\":\"2021-04-15T01:01:06+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#primaryimage\",\"url\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg\",\"contentUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.cabinet-magar.fr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/#website\",\"url\":\"https:\/\/www.cabinet-magar.fr\/\",\"name\":\"Cabinet Magar\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cabinet-magar.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union - Cabinet Magar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/","og_locale":"de_DE","og_type":"article","og_title":"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union - Cabinet Magar","og_description":"Les voyageurs souhaitant se rendre de Mayotte, de Guyane ou de la R\u00e9union vers le reste de la France doivent pr\u00e9senter une d\u00e9claration sur l\u2019honneur au transporteur. Le contenu de cette d\u00e9claration vient d\u2019\u00eatre pr\u00e9cis\u00e9. Que faut-il y mentionner ?","og_url":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/","og_site_name":"Cabinet Magar","article_published_time":"2021-01-18T04:59:00+00:00","article_modified_time":"2021-04-15T01:01:06+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#article","isPartOf":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/"},"author":{"name":"","@id":""},"headline":"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union","datePublished":"2021-01-18T04:59:00+00:00","dateModified":"2021-04-15T01:01:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/"},"wordCount":420,"commentCount":0,"image":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg","articleSection":["Actu Juridique","Actualit\u00e9s"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/","url":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/","name":"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union - Cabinet Magar","isPartOf":{"@id":"https:\/\/www.cabinet-magar.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#primaryimage"},"image":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg","datePublished":"2021-01-18T04:59:00+00:00","dateModified":"2021-04-15T01:01:06+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#primaryimage","url":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg","contentUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/cayenne.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/coronavirus-covid-19-du-nouveau-pour-les-voyageurs-en-provenance-de-mayotte-de-guyane-et-de-la-reunion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cabinet-magar.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Coronavirus (COVID-19) : du nouveau pour les voyageurs en provenance de Mayotte, de Guyane et de la R\u00e9union"}]},{"@type":"WebSite","@id":"https:\/\/www.cabinet-magar.fr\/#website","url":"https:\/\/www.cabinet-magar.fr\/","name":"Cabinet Magar","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cabinet-magar.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/comments?post=740"}],"version-history":[{"count":1,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/740\/revisions"}],"predecessor-version":[{"id":4024,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/740\/revisions\/4024"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/media\/4025"}],"wp:attachment":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/media?parent=740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/categories?post=740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/tags?post=740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}