{"id":685,"date":"2021-01-27T05:45:00","date_gmt":"2021-01-27T04:45:00","guid":{"rendered":"https:\/\/www.cabinet-magar.fr\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/"},"modified":"2021-04-12T03:00:54","modified_gmt":"2021-04-12T01:00:54","slug":"constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds","status":"publish","type":"post","link":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/","title":{"rendered":"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds"},"content":{"rendered":"<p >L\u2019Union europ\u00e9enne a d\u00e9cid\u00e9 de renforcer les mesures de contr\u00f4le des performances \u00e9nerg\u00e9tiques des v\u00e9hicules lourds. Que devez-vous savoir ?<\/p>\n<div>\n<h2>Constructeurs automobiles : les performances \u00e9nerg\u00e9tiques en question<\/h2>\n<p>Depuis le 1er janvier 2021, la r\u00e9glementation europ\u00e9enne relative aux contr\u00f4les des performances \u00e9nerg\u00e9tiques des v\u00e9hicules lourds est renforc\u00e9e.<\/p>\n<p>D\u00e9sormais, les essais de d\u00e9monstration doivent tenir compte des \u00e9missions de polluants pendant la p\u00e9riode de d\u00e9marrage du moteur \u00e0 froid, pour mieux repr\u00e9senter les \u00e9missions r\u00e9elles des v\u00e9hicules lourds.<\/p>\n<p>Par ailleurs, les v\u00e9hicules \u00e9quip\u00e9s de moteur \u00e0 allumage command\u00e9 ou de moteurs \u00e0 double carburant (dual fuel) aliment\u00e9s au gaz naturel comprim\u00e9 (GNC), au gaz naturel liqu\u00e9fi\u00e9 (GNL) ou au gaz de p\u00e9trole liqu\u00e9fi\u00e9 (GPL) peuvent n\u00e9cessiter des adaptations techniques pour respecter le facteur de conformit\u00e9 du nombre de particules \u00e9mis.<\/p>\n<p>Enfin, pour permettre aux constructeurs de moteurs de disposer d\u2019un d\u00e9lai suffisant pour modifier leurs produits et se mettre en conformit\u00e9 avec les nouvelles normes, une p\u00e9riode de transition leur est offerte jusqu\u2019au 1er janvier 2024.<\/p>\n<\/div>\n<p>Source : R\u00e8glement (UE) 2019\/1939 de la commission du 7 novembre 2019 modifiant le r\u00e8glement (UE) n 582\/2011 en en ce qui concerne les strat\u00e9gies auxiliaires de limitation des \u00e9missions (AES), l\u2019acc\u00e8s aux informations du syst\u00e8me OBD des v\u00e9hicules et aux informations sur la r\u00e9paration et l\u2019entretien des v\u00e9hicules, la mesure des \u00e9missions pendant les p\u00e9riodes de d\u00e9marrage du moteur \u00e0 froid et l\u2019utilisation de syst\u00e8mes portables de mesure des \u00e9missions (PEMS) pour mesurer le nombre de particules, pour les v\u00e9hicules lourds<\/p>\n<p><a href=\"https:\/\/www.weblex.fr\/weblex-actualite\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\" target=\"_blank\" rel=\"noopener\">Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds<\/a> \u00a9 Copyright WebLex &#8211; 2021<\/p>\n<p><img src='https:\/\/www.weblex.fr\/images\/flux_actus\/voitureconstruction.jpg'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Union europ\u00e9enne a d\u00e9cid\u00e9 de renforcer les mesures de contr\u00f4le des performances \u00e9nerg\u00e9tiques des v\u00e9hicules lourds. Que devez-vous savoir ?<\/p>\n","protected":false},"author":0,"featured_media":3921,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,7],"tags":[],"class_list":["post-685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-juridique","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds - Cabinet Magar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds - Cabinet Magar\" \/>\n<meta property=\"og:description\" content=\"L\u2019Union europ\u00e9enne a d\u00e9cid\u00e9 de renforcer les mesures de contr\u00f4le des performances \u00e9nerg\u00e9tiques des v\u00e9hicules lourds. Que devez-vous savoir ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabinet Magar\" \/>\n<meta property=\"article:published_time\" content=\"2021-01-27T04:45:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-12T01:00:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds\",\"datePublished\":\"2021-01-27T04:45:00+00:00\",\"dateModified\":\"2021-04-12T01:00:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/\"},\"wordCount\":301,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg\",\"articleSection\":[\"Actu Juridique\",\"Actualit\u00e9s\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/\",\"url\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/\",\"name\":\"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds - Cabinet Magar\",\"isPartOf\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg\",\"datePublished\":\"2021-01-27T04:45:00+00:00\",\"dateModified\":\"2021-04-12T01:00:54+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#primaryimage\",\"url\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg\",\"contentUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.cabinet-magar.fr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/#website\",\"url\":\"https:\/\/www.cabinet-magar.fr\/\",\"name\":\"Cabinet Magar\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cabinet-magar.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds - Cabinet Magar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/","og_locale":"de_DE","og_type":"article","og_title":"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds - Cabinet Magar","og_description":"L\u2019Union europ\u00e9enne a d\u00e9cid\u00e9 de renforcer les mesures de contr\u00f4le des performances \u00e9nerg\u00e9tiques des v\u00e9hicules lourds. Que devez-vous savoir ?","og_url":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/","og_site_name":"Cabinet Magar","article_published_time":"2021-01-27T04:45:00+00:00","article_modified_time":"2021-04-12T01:00:54+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#article","isPartOf":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/"},"author":{"name":"","@id":""},"headline":"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds","datePublished":"2021-01-27T04:45:00+00:00","dateModified":"2021-04-12T01:00:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/"},"wordCount":301,"commentCount":0,"image":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg","articleSection":["Actu Juridique","Actualit\u00e9s"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/","url":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/","name":"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds - Cabinet Magar","isPartOf":{"@id":"https:\/\/www.cabinet-magar.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#primaryimage"},"image":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg","datePublished":"2021-01-27T04:45:00+00:00","dateModified":"2021-04-12T01:00:54+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#primaryimage","url":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg","contentUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/voitureconstruction.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/constructeurs-automobiles-du-nouveau-pour-les-vehicules-lourds\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cabinet-magar.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Constructeurs automobiles : du nouveau pour les v\u00e9hicules lourds"}]},{"@type":"WebSite","@id":"https:\/\/www.cabinet-magar.fr\/#website","url":"https:\/\/www.cabinet-magar.fr\/","name":"Cabinet Magar","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cabinet-magar.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/comments?post=685"}],"version-history":[{"count":1,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/685\/revisions"}],"predecessor-version":[{"id":3920,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/685\/revisions\/3920"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/media\/3921"}],"wp:attachment":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/media?parent=685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/categories?post=685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/tags?post=685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}