{"id":1050,"date":"2020-12-01T05:46:00","date_gmt":"2020-12-01T04:46:00","guid":{"rendered":"https:\/\/www.cabinet-magar.fr\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/"},"modified":"2021-04-30T03:01:03","modified_gmt":"2021-04-30T01:01:03","slug":"produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement","status":"publish","type":"post","link":"https:\/\/www.cabinet-magar.fr\/de\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/","title":{"rendered":"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ?"},"content":{"rendered":"<p >Le Gouvernement peut d\u00e9cider de fixer aux laboratoires un prix maximal de vente de leurs produits aux \u00e9tablissements de sant\u00e9. Dans quelles conditions ?<\/p>\n<div>\n<h2>Prix maximal de vente des produits de sant\u00e9 : dans quelles conditions ?<\/h2>\n<p>Lorsque le Gouvernement envisage de fixer, pour une sp\u00e9cialit\u00e9 pharmaceutique ou un autre produit de sant\u00e9, un prix maximal de vente aux \u00e9tablissements de sant\u00e9, il doit en informer les laboratoires exploitant le produit concern\u00e9.<\/p>\n<p>Cette information est donn\u00e9e par tout moyen permettant de donner une date certaine \u00e0 sa r\u00e9ception (comme la lettre recommand\u00e9e avec accus\u00e9 de r\u00e9ception, par exemple), et doit pr\u00e9ciser : les produits de sant\u00e9 concern\u00e9s, les motifs de la fixation d&#8217;un prix maximal de vente et le niveau des prix envisag\u00e9s.<\/p>\n<p>Dans un d\u00e9lai de 20 jours suivant la r\u00e9ception de cette information, les laboratoires peuvent adresser au Gouvernement des observations \u00e9crites sur le projet de fixation d&#8217;un prix maximal de vente.<\/p>\n<p>Ils peuvent \u00e9galement demander, dans un d\u00e9lai de 8 jours suivant cette m\u00eame r\u00e9ception, \u00e0 pr\u00e9senter des observations orales sur ce projet. Dans ce cas, l&#8217;audition a lieu \u00e0 une date fix\u00e9e par le Gouvernement, au plus tard 45 jours apr\u00e8s la r\u00e9ception de la demande.<\/p>\n<p>Les prix maximaux de vente peuvent \u00eatre modifi\u00e9s par arr\u00eat\u00e9 minist\u00e9riel, soit \u00e0 la demande du laboratoire, soit \u00e0 l&#8217;initiative du Gouvernement, selon les modalit\u00e9s suivantes :<\/p>\n<ul>\n<li>lorsque la modification r\u00e9sulte de l&#8217;initiative du Gouvernement, elle intervient selon la proc\u00e9dure pr\u00e9cit\u00e9e ;<\/li>\n<li>lorsque la demande de modification du prix est form\u00e9e par le laboratoire, celui-ci adresse sa demande au Gouvernement accompagn\u00e9e d&#8217;un dossier comportant les informations n\u00e9cessaires \u00e0 l&#8217;appr\u00e9ciation de cette demande par voie \u00e9lectronique.<\/li>\n<\/ul>\n<p>La d\u00e9cision relative \u00e0 la demande de modification d&#8217;un prix maximal de vente est notifi\u00e9e au laboratoire dans un d\u00e9lai de 90 jours \u00e0 compter de la r\u00e9ception de cette demande.<\/p>\n<p>Si le nombre de demandes tendant \u00e0 la modification de prix est exceptionnellement \u00e9lev\u00e9, le d\u00e9lai peut \u00eatre prorog\u00e9 une seule fois de 60 jours.<\/p>\n<p>Si les \u00e9l\u00e9ments d&#8217;appr\u00e9ciation communiqu\u00e9s par le laboratoire sont insuffisants, la liste des renseignement compl\u00e9mentaires requis lui est imm\u00e9diatement notifi\u00e9e par le Gouvernement. Dans ce cas, le d\u00e9lai est suspendu \u00e0 compter de la r\u00e9ception de la notification et jusqu&#8217;\u00e0 la r\u00e9ception des renseignements compl\u00e9mentaires demand\u00e9s.<\/p>\n<p>A l&#8217;expiration des d\u00e9lais pr\u00e9cit\u00e9s, si aucune d\u00e9cision relative \u00e0 la modification du prix n&#8217;a \u00e9t\u00e9 notifi\u00e9e au laboratoire, la modification du prix est accord\u00e9e tacitement et est mentionn\u00e9e dans un avis publi\u00e9 au Journal officiel de la R\u00e9publique fran\u00e7aise.<\/p>\n<p>L&#8217;arr\u00eat\u00e9 minist\u00e9riel fixant ou modifiant un prix est motiv\u00e9 et publi\u00e9 au Journal officiel de la R\u00e9publique fran\u00e7aise.<\/p>\n<p>Enfin, le refus du Gouvernement d\u2019augmenter le prix maximal de vente sollicit\u00e9 par un laboratoire est notifi\u00e9 \u00e0 ce dernier, avec la mention des motifs de cette d\u00e9cision ainsi que des voies et d\u00e9lais de recours qui lui sont applicables.<\/p>\n<\/div>\n<p>Source : D\u00e9cret n\u00b0 2020-1437 du 24 novembre 2020 relatif aux modalit\u00e9s de fixation du prix maximal de vente aux \u00e9tablissements de sant\u00e9 d&#8217;un produit de sant\u00e9<\/p>\n<p><a href=\"https:\/\/www.weblex.fr\/weblex-actualite\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\" target=\"_blank\" rel=\"noopener\">Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ?<\/a> \u00a9 Copyright WebLex &#8211; 2020<\/p>\n<p><img src='https:\/\/www.weblex.fr\/images\/flux_actus\/medecinprix.jpg'><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Gouvernement peut d\u00e9cider de fixer aux laboratoires un prix maximal de vente de leurs produits aux \u00e9tablissements de sant\u00e9. Dans quelles conditions ?<\/p>\n","protected":false},"author":0,"featured_media":4531,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[9,7],"tags":[],"class_list":["post-1050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actu-juridique","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ? - Cabinet Magar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ? - Cabinet Magar\" \/>\n<meta property=\"og:description\" content=\"Le Gouvernement peut d\u00e9cider de fixer aux laboratoires un prix maximal de vente de leurs produits aux \u00e9tablissements de sant\u00e9. Dans quelles conditions ?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/\" \/>\n<meta property=\"og:site_name\" content=\"Cabinet Magar\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-01T04:46:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-04-30T01:01:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ?\",\"datePublished\":\"2020-12-01T04:46:00+00:00\",\"dateModified\":\"2021-04-30T01:01:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/\"},\"wordCount\":578,\"commentCount\":0,\"image\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg\",\"articleSection\":[\"Actu Juridique\",\"Actualit\u00e9s\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/\",\"url\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/\",\"name\":\"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ? - Cabinet Magar\",\"isPartOf\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg\",\"datePublished\":\"2020-12-01T04:46:00+00:00\",\"dateModified\":\"2021-04-30T01:01:03+00:00\",\"author\":{\"@id\":\"\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#primaryimage\",\"url\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg\",\"contentUrl\":\"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg\",\"width\":600,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.cabinet-magar.fr\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.cabinet-magar.fr\/#website\",\"url\":\"https:\/\/www.cabinet-magar.fr\/\",\"name\":\"Cabinet Magar\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.cabinet-magar.fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ? - Cabinet Magar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/","og_locale":"de_DE","og_type":"article","og_title":"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ? - Cabinet Magar","og_description":"Le Gouvernement peut d\u00e9cider de fixer aux laboratoires un prix maximal de vente de leurs produits aux \u00e9tablissements de sant\u00e9. Dans quelles conditions ?","og_url":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/","og_site_name":"Cabinet Magar","article_published_time":"2020-12-01T04:46:00+00:00","article_modified_time":"2021-04-30T01:01:03+00:00","og_image":[{"width":600,"height":400,"url":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#article","isPartOf":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/"},"author":{"name":"","@id":""},"headline":"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ?","datePublished":"2020-12-01T04:46:00+00:00","dateModified":"2021-04-30T01:01:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/"},"wordCount":578,"commentCount":0,"image":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg","articleSection":["Actu Juridique","Actualit\u00e9s"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/","url":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/","name":"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ? - Cabinet Magar","isPartOf":{"@id":"https:\/\/www.cabinet-magar.fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#primaryimage"},"image":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg","datePublished":"2020-12-01T04:46:00+00:00","dateModified":"2021-04-30T01:01:03+00:00","author":{"@id":""},"breadcrumb":{"@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#primaryimage","url":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg","contentUrl":"https:\/\/www.cabinet-magar.fr\/wp-content\/uploads\/2021\/04\/medecinprix.jpg","width":600,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.cabinet-magar.fr\/actualites\/produits-de-sante-un-prix-de-vente-fixe-par-le-gouvernement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.cabinet-magar.fr\/de\/"},{"@type":"ListItem","position":2,"name":"Produits de sant\u00e9 : un prix de vente fix\u00e9 par le Gouvernement ?"}]},{"@type":"WebSite","@id":"https:\/\/www.cabinet-magar.fr\/#website","url":"https:\/\/www.cabinet-magar.fr\/","name":"Cabinet Magar","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.cabinet-magar.fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/1050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/comments?post=1050"}],"version-history":[{"count":1,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/1050\/revisions"}],"predecessor-version":[{"id":4530,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/posts\/1050\/revisions\/4530"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/media\/4531"}],"wp:attachment":[{"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/media?parent=1050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/categories?post=1050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.cabinet-magar.fr\/de\/wp-json\/wp\/v2\/tags?post=1050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}